{"id":5720,"date":"2025-09-15T09:42:30","date_gmt":"2025-09-15T09:42:30","guid":{"rendered":"https:\/\/oracleconraul.com\/?p=5720"},"modified":"2025-12-18T09:58:12","modified_gmt":"2025-12-18T09:58:12","slug":"instalar-oracle-database-19c","status":"publish","type":"post","link":"https:\/\/oracleconraul.com\/index.php\/2025\/09\/15\/instalar-oracle-database-19c\/","title":{"rendered":"Instalar Oracle 19c Database paso a paso Linux"},"content":{"rendered":"\n<p>Este art\u00edculo describe los pasos para instalar Oracle Database 19c de 64 bits en Oracle Linux en Redhat 9 de 64 bits.<br>Partimos de que la versi\u00f3n de SSOO Redhat 9 ya ha sido instalada, puedes seguir este enlace donde se explica c\u00f3mo hacerlo.<br><a href=\"https:\/\/bdconraul.com\/instalacion-red-hat\/\">https:\/\/bdconraul.com\/instalacion-red-hat\/<\/a><\/p>\n\n\n\n<p><strong>1 . Descargar el software<\/strong><\/p>\n\n\n\n<p>Seg\u00fan del soporte que se disponga puedes descargar el sotware de oracle Database 19c desde OTN, edelivery o MOS.<\/p>\n\n\n\n<p><em>E-Delivery:<\/em><\/p>\n\n\n\n<p><a href=\"https:\/\/edelivery.oracle.com\/osdc\/faces\/Home.jspx\">https:\/\/edelivery.oracle.com\/osdc\/faces\/Home.jspx<\/a><br><em>OTN:<\/em><br><a href=\"https:\/\/www.oracle.com\/es\/database\/technologies\/oracle19c-linux-downloads.html\">https:\/\/www.oracle.com\/es\/database\/technologies\/oracle19c-linux-downloads.html<\/a><br>MOS<br><a href=\"https:\/\/support.oracle.com\/signin\">https:\/\/support.oracle.com\/signin<\/a><\/p>\n\n\n\n<p>En nuestro caso optamos por la opci\u00f3n OTN.<\/p>\n\n\n\n<p>Nos descargamos el fichero que se ajusta a nuestra arquitectura, en nuestro caso Linux-x86_64 bits:<\/p>\n\n\n\n<p class=\"has-text-color has-link-color wp-elements-6599e87e50bfdd02526ae94c8d59627f\" style=\"color:#3e87b7\"><strong>p37260974_190000_Linux-x86-64.zip<\/strong><\/p>\n\n\n\n<p>C\u00f3mo veremos despu\u00e9s, si intentas instalar directamente Oracle 19.3 en versiones Linux 9, podr\u00e1s caer en un bug, para ello es necesario aplicar un parche durante la instalaci\u00f3n.<br><br>Por ello necesitamos tambi\u00e9n decargar, la \u00faltima versi\u00f3n del Opath, que puedes descargar del siguuiente enlace.<br><br>1) Bajamos el OPatch de la siguiente direcci\u00f3n de Oracle.<br><br><em><a href=\"https:\/\/updates.oracle.com\/download\/6880880.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/updates.oracle.com\/download\/6880880.html<\/a><\/em><br><br>2) BUG FIX:<\/p>\n\n\n\n<p>Existe un parche crucial y \u00fanico para resolver errores que se producen durante la isntalaciones de Oracle 19c o Enterprise Manager (OEM) en Linux 9 (OL9) o en RHEL9, por tanto ser\u00e1 necsario apilcar el siguiente parche <em>(Patch 35775632)<\/em>:<\/p>\n\n\n\n<p><br><strong><em>Patch 35775632: PLACEHOLDER FOR STUBS.TAR PATCH FOR OL9 THAT FIXES BUG 33794281<\/em><\/strong><br><br>Puedes descargarte el parche el a siguiente direcci\u00f3n:<br><a href=\"https:\/\/support.oracle.com\/\">https:\/\/support.oracle.com\/<\/a><br><\/p>\n\n\n\n<p class=\"has-text-color has-link-color wp-elements-4489b03f90fbaecba6b4127bd43c790a\" style=\"color:#3e87b7\"><strong><a href=\"https:\/\/updates.oracle.com\/Orion\/Services\/download\/p35775632_190000_Linux-x86-64.zip?aru=25398250&amp;patch_file=p35775632_190000_Linux-x86-64.zip\" target=\"_blank\" rel=\"noreferrer noopener\">p35775632_190000_Linux-x86-64.zip&nbsp;<\/a><\/strong><\/p>\n\n\n\n<p><strong>2.Preparaci\u00f3n del entorno.<\/strong><\/p>\n\n\n\n<p>Puedes cambiar el nombre del hosts mediante comandos del sistema operativo  con hostnamectl (recomendo) o puedes editar manualmente los ficheros \u00ab\/etc\/hosts\u00bb y \u00ab<code>\/etc\/hostname<\/code>\u00ab. <\/p>\n\n\n\n<p>Para cambiar el nombre del host, ejecuta lo siguiente (c\u00f3mo root).<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\"><strong>hostnamectl set-hostname nuevo-host<\/strong><\/pre>\n\n\n\n<p>3<strong>. Instalamos los prerequisitos de software.<\/strong><\/p>\n\n\n\n<p>Para instalar los prerequisitos necesarios para una instalaci\u00f3n de una base de datos Oracle 19c, es muy aconsejable instalar el paquete oracle-database-preinstall-19c. <br>Este paquete de Linux<em> instala autom\u00e1ticamente todos los requisitos necesarios de sofware<\/em> (paquetes y dependencias), cambia y configura par\u00e1metros del sistema operativo, y crea usarios y grupos necesarios para poder instalar Oracle Dabase 19c \/ Oracle Grid infraestructure sin problemas.<br>En caso contrario, tendr\u00e1s que cambiar\/configurar todos los par\u00e1metros necesarios para la instalaci\u00f3n de forma manual, con lo cual, la instalaci\u00f3n de este paquete simplifica enormemente la instalaci\u00f3n del software de Oracle.<\/p>\n\n\n\n<p>Durante La instalaci\u00f3n del software, indicamos un nombre de host y una ip fija. <br><br> Nuestra configuraci\u00f3n es la siguiente.<br><strong>Nombre del host: oracle19cdb1<br>ipfija del servidor: 192.168.1.137<\/strong><\/p>\n\n\n\n<p>C\u00f3mo nos encontramos con RHEL9, descargamos el RPM de la siguiente manera (con acceso a internet).<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">curl -o oracle-database-preinstall-19c-1.0-1.el9.x86_64.rpm https:\/\/yum.oracle.com\/repo\/OracleLinux\/OL9\/appstream\/x86_64\/getPackage\/oracle-database-preinstall-19c-1.0-1.el9.x86_64.rpm<\/pre>\n\n\n\n<p>Instalamos el paquete recientemente descargado.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"505\" src=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-4-1024x505.png\" alt=\"\" class=\"wp-image-5738\" srcset=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-4-1024x505.png 1024w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-4-300x148.png 300w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-4-768x378.png 768w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-4.png 1175w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Antes de lanzar el instalador hay que tener en cuenta que el instalador de Oracle 19.3 no funciona correctamente en Linux 9.  Si se lanza el instalador directamente tras bajar el software es muy probable que caigas en este Bug.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"509\" height=\"234\" src=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-21.png\" alt=\"\" class=\"wp-image-5786\" srcset=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-21.png 509w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-21-300x138.png 300w\" sizes=\"(max-width: 509px) 100vw, 509px\" \/><\/figure>\n\n\n\n<p class=\"has-small-font-size\"><em>Este es el error que obtendr\u00e1s si intnentas instalar la versi\u00f3n 19.3<\/em>.<\/p>\n\n\n\n<p><strong>3- Preparaci\u00f3n del entorno antes de lanzar el instalador.<\/strong><\/p>\n\n\n\n<p>En primer lugar antes de aplicar el parche  actualizamos el fichero Opatch (<strong>unzip p6880880_230000_LINUX.zip<\/strong>), de la siguiente manera.<\/p>\n\n\n\n<p>Nos dirijimos al $ORACLE_HOME de nuestra instalaci\u00f3n, movemos el directorio Opatch a otro directorio con otro nombre, y descomprimimos el fichero<strong> <\/strong>p6880880_230000_LINUX.zip<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\"><strong>cd $ORACLE_HOME<\/strong><br>pwd<br>\/home\/oracle\/software\/dbhome19c<br>[oracle@oracle19cdb1 dbhome19c]$<strong> mv OPatch\/ OPatch_old<\/strong><br>oracle@oracle19cdb1 dbhome19c]$ <strong>unzip p6880880_230000_LINUX.zip<\/strong><br>Archive:  p6880880_230000_LINUX.zip<br>   creating: OPatch\/<br>   creating: OPatch\/oracle_common\/<br>   creating: OPatch\/oracle_common\/modules\/<br>  inflating: OPatch\/oracle_common\/modules\/com.oracle.glcm.common-logging_1.6.5.0.jar  <br>  inflating: OPatch\/oracle_common\/modules\/common-logging-config.jar  <br>  inflating: OPatch\/opatch_env.sh <\/pre>\n\n\n\n<p>Aplicar parche 35775632.<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">Para descargar el parche: Get Patch 35775632 (p35775632_190000_Linux-x86-64.zip) from My Oracle Support (MOS).<br><br>1 - Extraemos el parche descargado anteriormente.<br><strong>unzip p35775632_190000_Linux-x86-64.zip <\/strong><br><br><br><br>2 - Tras extraer el .zip, aparecer\u00e1 un fichero \"stubs.tar\". <br>Localiza este fichero y cop\u00edalo a t\u00fa $ORACLE_HOME\/lib\/stubs<br><br><strong>cp \/home\/oracle\/software\/35775632\/stubs.tar $ORACLE_HOME\/lib\/stubs<\/strong><br><br><br>3- Descomprime el fichero .tar que has copiado.<br><strong>cd $ORACLE_HOME\/lib\/stubs<\/strong><br><strong>tar -xf stubs.tar<\/strong><br><\/pre>\n\n\n\n<p><strong>4. Instalaci\u00f3n del software de base de datos 19c.<\/strong><\/p>\n\n\n\n<p>Antes de comenzar la isntalaci\u00f3n vamos a crear los directorios donde se realizar\u00e1 la Instalaci\u00f3n. Adem\u00e1s crearemos tambi\u00e9n un fichero de variables de entorno para no tener que ejecutar manualmente dichas variables cada vez que queramos acceder a nuestra base de datos.<br><br><strong><em>mkdir -p  \/u01\/app\/oracle\/product\/19.0.0\/dbhome_1<\/em><\/strong><\/p>\n\n\n\n<p>Descomprimimos el archivo LINUX.X64_193000_db_home.zip.<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">pwd<br>\/home\/oracle\/software\/dbhome19c<br>[oracle@oracle19cdb1 dbhome19c]$ <strong>unzip LINUX.X64_193000_db_home.zip<\/strong><\/pre>\n\n\n\n<p>Ejemplo de fichero con varibales de entorno test.env <em>(adecuar variables al entorno donde se est\u00e1 lanzando)<\/em><br><\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">cat test.env<br><br>export TMP=\/tmp<br>export TMPDIR=$TMP<br><br>export ORACLE_HOSTNAME=oracle19cdb1<br>export ORACLE_BASE=\/u01\/app\/oracle<br>export ORACLE_HOME=\/u01\/app\/oracle\/product\/19.0.0\/dbhome_1<br>export ORA_INVENTORY=\/u01\/app\/oraInventory<br>export ORACLE_SID=test<br>export PDB_NAME=testpdb1<br>export DATA_DIR=\/oradata<br><br>export PATH=\/usr\/sbin:\/usr\/local\/bin:$PATH<br>export PATH=$ORACLE_HOME\/bin:$PATH<br><br>export LD_LIBRARY_PATH=$ORACLE_HOME\/lib:\/lib:\/usr\/lib<br>export CLASSPATH=$ORACLE_HOME\/jlib:$ORACLE_HOME\/rdbms\/jlib<br><\/pre>\n\n\n\n<p>Una vez aplicado el parche ya podr\u00e1s lanzar el instalador.<\/p>\n\n\n\n<p>Ejecutamos el instalador con <strong>.\/runInstaller<\/strong><\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">oracle@oracle19cdb1 ~]$ <strong>. .\/test.env <\/strong><br><strong>export CV_ASSUME_DISTID=OEL7.8<\/strong><br><br>pwd<br>\/home\/oracle\/software\/dbhome19c<br>oracle@oracle19cdb1 dbhome19c]$ <strong>.\/runInstaller<\/strong><\/pre>\n\n\n\n<p>Para que no aparezca el siguiente error.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"509\" height=\"180\" src=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-5.png\" alt=\"\" class=\"wp-image-5748\" srcset=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-5.png 509w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-5-300x106.png 300w\" sizes=\"(max-width: 509px) 100vw, 509px\" \/><\/figure>\n\n\n\n<p><strong>[INS-08101] Unexpected error while executing the action at state: \u2018supportedOSCheck\u2019<\/strong><\/p>\n\n\n\n<p>A\u00f1ade la siguiente variable de entorno (CV_ASSUME_DISTID=OEL7.8) anes de ejecutar el instalador.<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\"><strong>export CV_ASSUME_DISTID=OEL7.8<\/strong><br><br>oracle@oracle19cdb1 dbhome19c]$ <strong>.\/runInstaller<\/strong><\/pre>\n\n\n\n<p>Ejecuci\u00f3n del instalador.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"605\" src=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-6.png\" alt=\"\" class=\"wp-image-5750\" srcset=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-6.png 801w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-6-300x227.png 300w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-6-768x580.png 768w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/figure>\n\n\n\n<p>Aparecen dos opciones, instalar software y crear una base de datos o \u00fanicamente instalar s\u00f3lo software. <br>Vamos a elegir la opci\u00f3n una, creando una base de datos de test.<br><br>Aparecen dos opciones.<br>La opci\u00f3n Escritorio es una instalaci\u00f3n m\u00e1s simple, para bases de datos de desarrollo con configuraci\u00f3n m\u00ednima para probar, aprender, etc. Con menos recuros m\u00e1s ideal para PCs, port\u00e1tiles, etc. La sgunda opci\u00f3n (clase Servidor) es ideal para entornos productivos y servidores, donde se busca mayor escabilidad y rendimiento, los recursos por tanto son mayores.<br><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"803\" height=\"611\" src=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-7.png\" alt=\"\" class=\"wp-image-5751\" srcset=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-7.png 803w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-7-300x228.png 300w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-7-768x584.png 768w\" sizes=\"(max-width: 803px) 100vw, 803px\" \/><\/figure>\n\n\n\n<p>Puedes elegir la opci\u00f3n que m\u00e1s se ajuste a tus necesidades, en nuestro caso elegiremos la segunda opci\u00f3n, ya que ser\u00e1 necesaria para la realizaci\u00f3n de post posteriores.<\/p>\n\n\n\n<p>En esta panatalla, elegiremos el directorio donde se instalar\u00e1 el sotware de base de datos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"612\" src=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-8.png\" alt=\"\" class=\"wp-image-5758\" srcset=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-8.png 801w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-8-300x229.png 300w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-8-768x587.png 768w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/figure>\n\n\n\n<p>En esta pantalla indicaremos donde se encontrar\u00e1 el inventario de nuestro software.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"609\" src=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-9.png\" alt=\"\" class=\"wp-image-5761\" srcset=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-9.png 799w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-9-300x229.png 300w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-9-768x585.png 768w\" sizes=\"(max-width: 799px) 100vw, 799px\" \/><\/figure>\n\n\n\n<p>Elegimos el tipo de base de datos que vamos a crear.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"802\" height=\"606\" src=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-10.png\" alt=\"\" class=\"wp-image-5763\" srcset=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-10.png 802w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-10-300x227.png 300w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-10-768x580.png 768w\" sizes=\"(max-width: 802px) 100vw, 802px\" \/><\/figure>\n\n\n\n<p>Especificamos los datos de nuestra base de datos, a la que llamaremos test. Esta base de datos ser\u00e1 creada c\u00f3mo arquitectura multitenant, por lo que elegiremos la opci\u00f3n \u00abCrear como base de datos contenedor\u00bb, y crearemos un nuevo contenedor, en nuestro caso \u00abtestpdb1\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"602\" src=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-11.png\" alt=\"\" class=\"wp-image-5765\" srcset=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-11.png 799w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-11-300x226.png 300w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-11-768x579.png 768w\" sizes=\"(max-width: 799px) 100vw, 799px\" \/><\/figure>\n\n\n\n<p>Especificamos las caracter\u00edsticas que tendr\u00e1 nuestra base de datos. <br>Memoria, juego de caracteres, etc.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"610\" src=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-12.png\" alt=\"\" class=\"wp-image-5767\" srcset=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-12.png 800w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-12-300x229.png 300w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-12-768x586.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Elelgimos donde se almacenar\u00e1n nuestros ficheros de base de datos. Son los ficheros f\u00edsicos donde se almacenar\u00e1 nuestra base de datos.<br>En nuestro caso se almacenar\u00e1n en un file system aparte del espacio donde se instalar\u00e1 el software de base de datos (recomendado).<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"794\" height=\"603\" src=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-13.png\" alt=\"\" class=\"wp-image-5771\" srcset=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-13.png 794w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-13-300x228.png 300w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-13-768x583.png 768w\" sizes=\"(max-width: 794px) 100vw, 794px\" \/><\/figure>\n\n\n\n<p>Activa o desactivar flash_recovery_area. Activa \/desactiva esta opci\u00f3n, que permite centralizar autom\u00e1ticamente y as\u00ed simplificar y acelear las tares de copias de sguridad y recuperaci\u00f3n ante desastres.<br><br><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"790\" height=\"603\" src=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-15.png\" alt=\"\" class=\"wp-image-5775\" srcset=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-15.png 790w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-15-300x229.png 300w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-15-768x586.png 768w\" sizes=\"(max-width: 790px) 100vw, 790px\" \/><\/figure>\n\n\n\n<p>INciamos las password de los usaurios administradores.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"797\" height=\"606\" src=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-16.png\" alt=\"\" class=\"wp-image-5777\" srcset=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-16.png 797w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-16-300x228.png 300w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-16-768x584.png 768w\" sizes=\"(max-width: 797px) 100vw, 797px\" \/><\/figure>\n\n\n\n<p>Especifica usuarios y grupos del sistema operativo, seg\u00fan requerimientos de vuestro sistema (dba,oper,oinstall, etc).<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"796\" height=\"599\" src=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-23.png\" alt=\"\" class=\"wp-image-5801\" srcset=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-23.png 796w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-23-300x226.png 300w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-23-768x578.png 768w\" sizes=\"(max-width: 796px) 100vw, 796px\" \/><\/figure>\n\n\n\n<p>Ejecuci\u00f3n de script con credenciales root.<\/p>\n\n\n\n<p>Para que la instalaci\u00f3n sea correcta, el instalador debe de realizar alguna acci\u00f3n sobre nuestro sistema con el usuario root. Puedes indicar al instalador que lo ejecute de forma autom\u00e1tica (se requieren credenciales) o ejecutarlo de forma manual una vez la instalaci\u00f3n haya finalizado.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"587\" height=\"328\" src=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-24.png\" alt=\"\" class=\"wp-image-5803\" srcset=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-24.png 587w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-24-300x168.png 300w\" sizes=\"(max-width: 587px) 100vw, 587px\" \/><\/figure>\n\n\n\n<p>Aparecer\u00e1 el resumen de nuestra instalaci\u00f3n, revisaremos que todo est\u00e1 correcto y comenzaremos la isntalaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"605\" src=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-20.png\" alt=\"\" class=\"wp-image-5783\" srcset=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-20.png 799w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-20-300x227.png 300w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-20-768x582.png 768w\" sizes=\"(max-width: 799px) 100vw, 799px\" \/><\/figure>\n\n\n\n<p>Finalmente aparecer\u00e1 un mensaje indicando que la isntalaci\u00f3n se ha realizado correctamente.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"597\" height=\"66\" src=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-26.png\" alt=\"\" class=\"wp-image-5806\" srcset=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-26.png 597w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/12\/image-26-300x33.png 300w\" sizes=\"(max-width: 597px) 100vw, 597px\" \/><\/figure>\n\n\n\n<p><strong>5. Conectarnos a la base de datos.<\/strong><\/p>\n\n\n\n<p>La forma de conectarnos a nuestra pdb  recien creada de forma directa mediate sqlplus es la siguiente.<br><em>sqlplus usuario\/password@host:puerto\/nombrepdb<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">oracle@oracle19cdb1 ~]$ <strong>sqlplus system\/oracleconraul@oracle19cdb1:1521\/testpdb1<\/strong><br>SQL*Plus: Release 19.0.0.0.0 - Production on Tue Dec 16 01:48:56 2025<br>Version 19.3.0.0.0<br><br>Copyright (c) 1982, 2019, Oracle.  All rights reserved.<br><br><br>Connected to:<br>Oracle Database 19c Enterprise Edition Release 19.0.0.0.0 - Production<br>Version 19.3.0.0.0<br><br><br><\/pre>\n\n\n\n<p>Lo habitual no es conectarte directamente a la base de datos, sino crear un tnsnames.ora y conecarte con alg\u00fan entorno de desarrollo, lo m\u00e1s habitual sqldeveloper.<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\"><em>Ejemplo fichero tnsnames.ora<\/em><br><br>[oracle@oracle19cdb1 ~]$ . oraenv<br>ORACLE_SID = [test] ? test<br>The Oracle base remains unchanged with value \/home\/oracle\/software<br>[oracle@oracle19cdb1 ~]$ <strong>cd $TNS_ADMIN<\/strong><br>[oracle@oracle19cdb1 admin]$ cat tnsnames.ora <br><strong>testpdb1 =<br>  (DESCRIPTION =<br>    (ADDRESS = (PROTOCOL = TCP)(HOST = oracle19cdb1)(PORT = 1521))<br>    (CONNECT_DATA =<br>      (SERVER = DEDICATED)<br>      (SERVICE_NAME = testpdb1)<br>    )<br>  )<br><\/strong><\/pre>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"783\" height=\"502\" src=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/09\/image.png\" alt=\"\" class=\"wp-image-5861\" srcset=\"https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/09\/image.png 783w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/09\/image-300x192.png 300w, https:\/\/oracleconraul.com\/wp-content\/uploads\/2025\/09\/image-768x492.png 768w\" sizes=\"(max-width: 783px) 100vw, 783px\" \/><\/figure>\n\n\n\n<p>Elegimos un nombre de conexi\u00f3n, tipo de conexi\u00f3n TNS y buscamos el nombre del alias de nuestro tnsnames.ora. Proporcionamos usuario\/password.y ya podremos conectarnos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este art\u00edculo describe los pasos para instalar Oracle Database 19c de 64 bits en Oracle Linux en Redhat 9 de 64 bits.Partimos de que la versi\u00f3n de SSOO Redhat 9 ya ha sido instalada, puedes seguir este enlace donde se explica c\u00f3mo hacerlo.https:\/\/bdconraul.com\/instalacion-red-hat\/ 1 . Descargar el software Seg\u00fan del soporte que se disponga puedes<\/p>\n<div class=\"more-link\">\n\t\t\t\t <a href=\"https:\/\/oracleconraul.com\/index.php\/2025\/09\/15\/instalar-oracle-database-19c\/\" class=\"link-btn theme-btn\"><span>Read More <\/span> <i class=\"fa fa-caret-right\"><\/i><\/a>\n\t\t\t<\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpupg_custom_link":[],"wpupg_custom_link_behaviour":[],"wpupg_custom_link_nofollow":[],"wpupg_custom_image":[],"wpupg_custom_image_id":[],"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[14],"tags":[15],"class_list":["post-5720","post","type-post","status-publish","format-standard","hentry","category-oracle","tag-rdbmsoracle"],"_links":{"self":[{"href":"https:\/\/oracleconraul.com\/index.php\/wp-json\/wp\/v2\/posts\/5720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oracleconraul.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oracleconraul.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oracleconraul.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oracleconraul.com\/index.php\/wp-json\/wp\/v2\/comments?post=5720"}],"version-history":[{"count":114,"href":"https:\/\/oracleconraul.com\/index.php\/wp-json\/wp\/v2\/posts\/5720\/revisions"}],"predecessor-version":[{"id":5871,"href":"https:\/\/oracleconraul.com\/index.php\/wp-json\/wp\/v2\/posts\/5720\/revisions\/5871"}],"wp:attachment":[{"href":"https:\/\/oracleconraul.com\/index.php\/wp-json\/wp\/v2\/media?parent=5720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oracleconraul.com\/index.php\/wp-json\/wp\/v2\/categories?post=5720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oracleconraul.com\/index.php\/wp-json\/wp\/v2\/tags?post=5720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}